{"id":60142339,"date":"2026-07-14T18:09:56","date_gmt":"2026-07-14T17:09:56","guid":{"rendered":"https:\/\/dialogue.earth\/uncategorized\/brasilia-residents-forced-to-grow-their-own-heat-solutions-2\/"},"modified":"2026-07-14T20:50:43","modified_gmt":"2026-07-14T19:50:43","slug":"periferia-brasilia-plantio-guerrilha-calor","status":"publish","type":"photo_story","link":"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/","title":{"rendered":"Periferia de Bras\u00edlia faz &#8216;plantio de guerrilha&#8217; contra o calor"},"content":{"rendered":"\n<p>Bras\u00edlia foi projetada para ser uma cidade verde. No plano urban\u00edstico da capital brasileira, inaugurada em 1960, a arboriza\u00e7\u00e3o era t\u00e3o central que ela foi descrita como \u201c<a href=\"https:\/\/pdad.ipe.df.gov.br\/files\/reports\/plano_piloto_eobnOtj.pdf\">cidade-parque<\/a>\u201d. Isso fica evidente no Plano Piloto, \u00e1rea central nobre com avenidas arborizadas e parques verdes por onde caminham moradores.<\/p>\n\n\n\n<p>Por\u00e9m, a 30 quil\u00f4metros dali, no Sol Nascente, uma das <a href=\"https:\/\/www.poder360.com.br\/poder-brasil\/2a-maior-favela-do-brasil-sol-nascente-vive-sob-contrastes\/\">maiores<\/a> favelas do pa\u00eds, o concreto tomou o lugar do Cerrado. A favela \u00e9 formada por quarteir\u00f5es de ruas majoritariamente asfaltadas, com casas que se amontoam umas sobre as outras e cal\u00e7adas estreitas que mal comportam pedestres, quanto mais \u00e1rvores.<\/p>\n\n\n\n<p>\u201cTem horas que a rua toda est\u00e1 no sol e o ar n\u00e3o circula\u201d, disse Francisco Silva, 34, em frente \u00e0 sua casa no Sol Nascente.&nbsp;<\/p>\n\n\n\n<p>Para aliviar o calor, Silva est\u00e1 reformando a pr\u00f3pria casa: o concreto vai dar lugar a grama e mudas. Na cal\u00e7ada, quebrou o cimento para plantar a \u00fanica \u00e1rvore da rua \u2014 um ip\u00ea solit\u00e1rio. No per\u00edodo seco, ele lava o quintal todo dia, espalha toalhas molhadas pela casa e usa m\u00e1scara contra a poeira.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-cd-story-image aligncenter block--story-image block--story-image--article\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><div class=\"block--story-image__column\"><div class=\"block--story-image__image\"><img class=\"lazy\" data-src=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_street-no-trees_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\" data-srcset=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_street-no-trees_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-768x512.jpg 768w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_street-no-trees_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1024x683.jpg 1024w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_street-no-trees_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1400x934.jpg 1400w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_street-no-trees_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1800x1200.jpg 2000w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_street-no-trees_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\" data-sizes=\"(max-width: 600px) 768px, (max-width: 999px) 1024px, (max-width: 1400px) 1400px, (max-width: 2000px) 2000px, 2560px\" alt=\"homem caminha por favela do Sol Nascente\"\/><\/div><div class=\"block--story-image__content\"><div itemprop=\"caption\" class=\"block--story-image__caption\">Uma das maiores favelas do pa\u00eds, Sol Nascente tem uma paisagem formada por ruas asfaltadas e poucas \u00e1rvores (Imagem: <a href=\"https:\/\/pozzebom.com.br\/\">Fabio Pozzebom<\/a> \/ Dialogue Earth)<\/div><\/div><\/div><meta itemprop=\"contentUrl\" content=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_street-no-trees_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\"\/><meta itemprop=\"contentSize\" content=\"2 MB\"\/><meta itemprop=\"height\" content=\"1707\"\/><meta itemprop=\"width\" content=\"2560\"\/><meta itemprop=\"author\"\/><meta itemprop=\"representativeOfPage\" content=\"true\"\/><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-cd-story-image aligncenter block--story-image block--story-image--article\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><div class=\"block--story-image__column\"><div class=\"block--story-image__image\"><img class=\"lazy\" data-src=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_trees-street_Asa-Norte_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-3.jpg\" data-srcset=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_trees-street_Asa-Norte_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-3-768x512.jpg 768w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_trees-street_Asa-Norte_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-3-1024x683.jpg 1024w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_trees-street_Asa-Norte_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-3-1400x934.jpg 1400w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_trees-street_Asa-Norte_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-3-1800x1200.jpg 2000w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_trees-street_Asa-Norte_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-3.jpg\" data-sizes=\"(max-width: 600px) 768px, (max-width: 999px) 1024px, (max-width: 1400px) 1400px, (max-width: 2000px) 2000px, 2560px\" alt=\"Rua arborizada do Plano Piloto, no centro de Bras\u00edlia\"\/><\/div><div class=\"block--story-image__content\"><div itemprop=\"caption\" class=\"block--story-image__caption\">J\u00e1 a \u00e1rea do Plano Piloto, no centro de Bras\u00edlia, tem grandes parques e ruas arborizadas (Imagem: <a href=\"https:\/\/pozzebom.com.br\/\">Fabio Pozzebom<\/a> \/ Dialogue Earth)<\/div><\/div><\/div><meta itemprop=\"contentUrl\" content=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_trees-street_Asa-Norte_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-3.jpg\"\/><meta itemprop=\"contentSize\" content=\"2 MB\"\/><meta itemprop=\"height\" content=\"1707\"\/><meta itemprop=\"width\" content=\"2560\"\/><meta itemprop=\"author\"\/><meta itemprop=\"representativeOfPage\" content=\"true\"\/><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-cd-story-image aligncenter block--story-image block--story-image--wide\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><div class=\"block--story-image__column\"><div class=\"block--story-image__image\"><img class=\"lazy\" data-src=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Francisco-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\" data-srcset=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Francisco-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-768x512.jpg 768w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Francisco-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1024x683.jpg 1024w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Francisco-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1400x934.jpg 1400w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Francisco-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1800x1200.jpg 2000w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Francisco-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\" data-sizes=\"(max-width: 600px) 768px, (max-width: 999px) 1024px, (max-width: 1400px) 1400px, (max-width: 2000px) 2000px, 2560px\" alt=\"Francisco Silva, morador de Sol Nascente, quebrou o cimento da cal\u00e7ada para plantar um ip\u00ea\"\/><\/div><div class=\"block--story-image__content\"><div itemprop=\"caption\" class=\"block--story-image__caption\">Francisco Silva, morador de Sol Nascente, quebrou o cimento da cal\u00e7ada para plantar um ip\u00ea \u2014 \u00fanica \u00e1rvore da rua (Imagem: <a href=\"https:\/\/pozzebom.com.br\/\">Fabio Pozzebom<\/a> \/ Dialogue Earth)<\/div><\/div><\/div><meta itemprop=\"contentUrl\" content=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Francisco-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\"\/><meta itemprop=\"contentSize\" content=\"2 MB\"\/><meta itemprop=\"height\" content=\"1707\"\/><meta itemprop=\"width\" content=\"2560\"\/><meta itemprop=\"author\"\/><meta itemprop=\"representativeOfPage\" content=\"true\"\/><\/div>\n\n\n\n<p>\u201cFica tudo muito seco, o nariz sangra\u201d, disse Silva, que sofre com rinite e bronquite, o que o leva a acordar v\u00e1rias vezes \u00e0 noite. \u201cSe fechar a janela, sufoca; se abrir, entra vento seco e terra\u201d.&nbsp;<\/p>\n\n\n\n<p>No Plano Piloto, a m\u00e9dia de \u00e1rea verde por habitante \u00e9 de 138 m\u00b2, segundo um <a href=\"https:\/\/www.researchgate.net\/profile\/Valdir-Steinke\/publication\/397117401_Revista_Brasileira_de_Geografia_Fisica_v18_n06_2025_4825-4848_Revista_Brasileira_de_Geografia_Fisica_v18_n06\/links\/69051a96a404d65709a16828\/Revista-Brasileira-de-Geografia-Fisica-v18-n06-2025-4825-4848-Revista-Brasileira-de-Geografia-Fisica-v18-n06.pdf\">estudo<\/a> de 2025. J\u00e1 em algumas \u00e1reas perif\u00e9ricas de Bras\u00edlia, como Sol Nascente, a oferta de vegeta\u00e7\u00e3o \u00e9 23 vezes menor, inferior a 6 m\u00b2.&nbsp;<\/p>\n\n\n\n<p>Valdir Steinke, autor da pesquisa pela Universidade de Bras\u00edlia (UnB) e especialista em paisagens e gest\u00e3o de recursos h\u00eddricos, diz que o Distrito Federal (DF) reflete um padr\u00e3o nacional: \u201c\u00e1reas verdes concentradas nas regi\u00f5es mais nobres, e periferias sem quase nada\u201d. A renda m\u00e9dia per capita das fam\u00edlias no Plano Piloto \u00e9 <a href=\"https:\/\/www.ipe.df.gov.br\/documents\/d\/ipedf\/informe-distrital-de-rendimentos\">12 vezes maior<\/a> que a do Sol Nascente.&nbsp;<\/p>\n\n\n\n<p>\u201c\u00c9 o retrato nu e cru de um modelo de segrega\u00e7\u00e3o socioecon\u00f4mica em que o planejamento urbano das periferias ignora a natureza\u201d, afirmou ao <em>Dialogue Earth.<\/em><\/p>\n\n\n\n<iframe src='https:\/\/flo.uri.sh\/visualisation\/29688225\/embed' title='Interactive or visual content' class='flourish-embed-iframe' frameborder='0' scrolling='no' style='width:100%;aspect-ratio:1.3;' sandbox='allow-same-origin allow-forms allow-scripts allow-downloads allow-popups allow-popups-to-escape-sandbox allow-top-navigation-by-user-activation'><\/iframe>\n\n\n\n<p>Esses problemas est\u00e3o se agravando \u00e0 medida que as mudan\u00e7as clim\u00e1ticas elevam as temperaturas e <a href=\"https:\/\/pmc.ncbi.nlm.nih.gov\/articles\/PMC12039654\/\">aumentam os problemas<\/a> de sa\u00fade. Diante dessas preocupa\u00e7\u00f5es, o governo do DF planeja um programa de plantio de \u00e1rvores, e moradores recorrem ao \u201cplantio de guerrilha\u201d onde o planejamento urbano tem falhado.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-desigualdade-verde-e-desafio-mundial\">Desigualdade verde \u00e9 desafio mundial<\/h2>\n\n\n\n<p>Sol Nascente surgiu nos anos 1990 em terras rurais ocupadas de forma irregular. Hoje, <a href=\"https:\/\/agenciadenoticias.ibge.gov.br\/media\/com_mediaibge\/arquivos\/2e500e343e167fe11fab25458569750c.pdf\">mais de 70 mil pessoas<\/a> habitam 9 km\u00b2 \u2014 densidade populacional quase 16 vezes maior que a m\u00e9dia do DF. Com o asfalto, a pouca vegeta\u00e7\u00e3o e a alta concentra\u00e7\u00e3o de moradores, a favela re\u00fane condi\u00e7\u00f5es ideais, segundo pesquisadores, para a forma\u00e7\u00e3o de ilhas de calor urbanas.<\/p>\n\n\n\n<p>\u201cO concreto e o asfalto absorvem e ret\u00eam o calor do sol com mais efici\u00eancia do que a vegeta\u00e7\u00e3o, enquanto as \u00e1rvores proporcionam resfriamento pela sombra e umidade\u201d, explicou Gregory Wellenius, diretor do Centro para o Clima e a Sa\u00fade da Universidade de Boston.<\/p>\n\n\n\n<div class=\"wp-block-cd-accordion block--accordion\"><span class=\"block--accordion__title\"><strong>O que s\u00e3o ilhas de calor urbanas?<\/strong><\/span><div class=\"block--accordion__content\"><div class=\"block--accordion__content__inner\">\n<p>Em grandes \u00e1reas urbanas, o efeito de ilha de calor consiste em um fen\u00f4meno no qual algumas \u00e1reas das cidades apresentam temperaturas mais altas do que outras. H\u00e1 alguns motivos para isso: excesso de superf\u00edcies asfaltadas ou constru\u00eddas com outros materiais que absorvem calor; a queima de combust\u00edvel e outros processos humanos que geram calor; e a aus\u00eancia de vegeta\u00e7\u00e3o. As ilhas de calor podem agravar a intensidade das ondas de calor em \u00e1reas urbanas.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<p>O que acontece no Sol Nascente segue um padr\u00e3o global, como mostra um <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/abs\/pii\/S2210670726002647\">estudo<\/a> recente publicado no peri\u00f3dico Sustainable Cities and Society. Ao analisar 199 cidades ao redor do mundo, ele concluiu que a desigualdade no acesso a \u00e1reas verdes \u00e9 generalizada, mas que o n\u00edvel da disparidade em cidades do Sul Global \u00e9 o dobro em rela\u00e7\u00e3o ao Norte Global.&nbsp;<\/p>\n\n\n\n<p>Dados mais espec\u00edficos sobre o problema s\u00e3o mais limitados no Sul Global. Em pa\u00edses do Norte Global, embora menos acentuada, a desigualdade verde separa bairros de alta e baixa renda. Um <a href=\"https:\/\/www.sciencedirect.com\/science\/article\/pii\/S1618866725002730\">estudo<\/a> identificou nas periferias de Nova York e Londres as maiores desigualdades de acesso ao verde dessas cidades. Nos Estados Unidos, <a href=\"https:\/\/journals.plos.org\/plosone\/article?id=10.1371\/journal.pone.0249715\">92% dos bairros pobres<\/a> t\u00eam menos \u00e1rvores e s\u00e3o mais quentes que as \u00e1reas nobres, segundo outro estudo.<\/p>\n\n\n\n<p>\u201cOs mapas de calor extremo se parecem muito com os mapas de bairros com poucos recursos\u201d, disse ao <em>Dialogue Earth<\/em> Jeremy Hoffman, pesquisador da Groundwork USA, rede de organiza\u00e7\u00f5es americanas que atuam por justi\u00e7a clim\u00e1tica. \u201cOs pontos cr\u00edticos de calor tendem a se sobrepor a \u00e1reas com mais pobreza, menor escolaridade, mais incid\u00eancia de doen\u00e7as cr\u00f4nicas e menos acesso a espa\u00e7os verdes\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-regra-3-30-300\">Regra 3-30-300<\/h2>\n\n\n\n<p>Foi para enfrentar a desigualdade verde nas cidades que o holand\u00eas Cecil Konijnendijk, especialista em florestas urbanas e professor honor\u00e1rio da Universidade da Col\u00fambia Brit\u00e2nica, no Canad\u00e1, <a href=\"https:\/\/www.330300rule.com\/\">prop\u00f4s<\/a> a \u201cregra 3-30-300\u201d. Criada em 2021, a diretriz estabelece que todo indiv\u00edduo deveria avistar ao menos tr\u00eas \u00e1rvores da janela de casa, viver em um bairro com ao menos 30% de cobertura arb\u00f3rea e morar a no m\u00e1ximo 300 metros de um parque ou \u00e1rea verde \u2014 m\u00e9tricas que buscam garantir acesso visual e f\u00edsico \u00e0 natureza e a seus benef\u00edcios.<\/p>\n\n\n\n<div class=\"wp-block-cd-story-image aligncenter block--story-image block--story-image--wide\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><div class=\"block--story-image__column\"><div class=\"block--story-image__image\"><img class=\"lazy\" data-src=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Olhos-D-agua-park_Asa-Norte_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\" data-srcset=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Olhos-D-agua-park_Asa-Norte_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-768x512.jpg 768w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Olhos-D-agua-park_Asa-Norte_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1024x683.jpg 1024w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Olhos-D-agua-park_Asa-Norte_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1400x934.jpg 1400w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Olhos-D-agua-park_Asa-Norte_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1800x1200.jpg 2000w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Olhos-D-agua-park_Asa-Norte_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\" data-sizes=\"(max-width: 600px) 768px, (max-width: 999px) 1024px, (max-width: 1400px) 1400px, (max-width: 2000px) 2000px, 2560px\" alt=\"Parque Olhos d\u2019\u00c1gua, Asa Norte, Plano Piloto\"\/><\/div><div class=\"block--story-image__content\"><div itemprop=\"caption\" class=\"block--story-image__caption\">Parque Olhos d\u2019\u00c1gua, Asa Norte, Plano Piloto. A regra &#8216;3-30-300&#8217;, do urbanista Cecil Konijnendijk, diz que cada pessoa deveria avistar ao menos tr\u00eas \u00e1rvores da janela de casa, viver em um bairro com 30% de cobertura arb\u00f3rea e morar a 300 metros de uma \u00e1rea verde (Imagem: <a href=\"https:\/\/pozzebom.com.br\/\">Fabio Pozzebom<\/a> \/ Dialogue Earth)<\/div><\/div><\/div><meta itemprop=\"contentUrl\" content=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Olhos-D-agua-park_Asa-Norte_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\"\/><meta itemprop=\"contentSize\" content=\"2 MB\"\/><meta itemprop=\"height\" content=\"1707\"\/><meta itemprop=\"width\" content=\"2560\"\/><meta itemprop=\"author\"\/><meta itemprop=\"representativeOfPage\" content=\"true\"\/><\/div>\n\n\n\n<p>A regra tem sido adotada por planejadores urbanos ao redor do mundo, <a href=\"https:\/\/www.330300rule.com\/implementation\/\">orientando<\/a> pol\u00edticas de arboriza\u00e7\u00e3o na B\u00e9lgica, Su\u00e9cia, Holanda, Estados Unidos e Canad\u00e1.&nbsp;<\/p>\n\n\n\n<p>No Brasil, o <a href=\"https:\/\/movimentoeconomico.com.br\/meio-ambiente\/2025\/11\/13\/cop30-brasil-lanca-plano-nacional-para-aumentar-arborizacao-urbana\/\">Plano Nacional de Arboriza\u00e7\u00e3o Urbana<\/a>, lan\u00e7ado na confer\u00eancia clim\u00e1tica COP30 em 2025, se inspira na regra. O documento reconhece que a urbaniza\u00e7\u00e3o desordenada do pa\u00eds resultou em fragmenta\u00e7\u00e3o de paisagens, desmatamento e solos impermeabilizados pelo concreto, o que, somado \u00e0s mudan\u00e7as clim\u00e1ticas, geram impactos negativos \u00e0 vida urbana.&nbsp;<\/p>\n\n\n\n<p>Para reverter esse quadro, o plano define metas at\u00e9 2045, entre elas a de elevar de 45,5% para 65% a propor\u00e7\u00e3o de moradores com ao menos tr\u00eas \u00e1rvores no entorno, o que representaria cerca de 40 milh\u00f5es de pessoas a mais com acesso ao verde. Ainda n\u00e3o est\u00e1 claro quais mudan\u00e7as isso traria para o Sol Nascente ou o Plano Piloto.<\/p>\n\n\n\n<p>Alguns especialistas questionam se a regra seria aplic\u00e1vel fora do Hemisf\u00e9rio Norte. Paulina Achurra, da plataforma de ensino Arq.Futuro, <a href=\"https:\/\/www.insper.edu.br\/pt\/noticias\/2024\/5\/inovacoes-para-enfrentar-as-mudancas-climaticas-em-territorios-v\">alertou<\/a> que uma solu\u00e7\u00e3o como essa n\u00e3o funcionaria em comunidades onde \u201cmal existe uma cal\u00e7ada para plantar uma \u00e1rvore\u201d.&nbsp;<\/p>\n\n\n\n<p>\u201cEmbora faltem solu\u00e7\u00f5es inovadoras que incluam o verde, elas devem ser plaus\u00edveis de aplica\u00e7\u00e3o nas nossas cidades. E esses s\u00e3o os desafios das cidades do Sul Global\u201d, disse Achurra em um evento em S\u00e3o Paulo.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-calor-extremo-traz-riscos-a-saude\">Calor extremo traz riscos \u00e0 sa\u00fade<\/h2>\n\n\n\n<p>Larissa Brenda Cordeiro coordena o instituto de justi\u00e7a socioambiental Filhas da Terra em Sol Nascente. Ela diz que o calor da tarde chega a ser t\u00e3o forte que inviabiliza as atividades do \u00f3rg\u00e3o, como reuni\u00f5es. Asm\u00e1tica e com fibromialgia, o calor lhe provoca dores nos m\u00fasculos e nas articula\u00e7\u00f5es. \u201cPasso muito mal tanto no frio como em per\u00edodos de muito calor\u201d, disse.<\/p>\n\n\n\n<div class=\"wp-block-cd-story-image aligncenter block--story-image block--story-image--wide\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><div class=\"block--story-image__column\"><div class=\"block--story-image__image\"><img class=\"lazy\" data-src=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Larissa-Brenda-Cordeiro_Parque-Urbano-setor-O_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\" data-srcset=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Larissa-Brenda-Cordeiro_Parque-Urbano-setor-O_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-768x512.jpg 768w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Larissa-Brenda-Cordeiro_Parque-Urbano-setor-O_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1024x683.jpg 1024w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Larissa-Brenda-Cordeiro_Parque-Urbano-setor-O_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1400x934.jpg 1400w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Larissa-Brenda-Cordeiro_Parque-Urbano-setor-O_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1800x1200.jpg 2000w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Larissa-Brenda-Cordeiro_Parque-Urbano-setor-O_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\" data-sizes=\"(max-width: 600px) 768px, (max-width: 999px) 1024px, (max-width: 1400px) 1400px, (max-width: 2000px) 2000px, 2560px\" alt=\"Larissa Brenda Cordeiro, presidente do Instituto Filhas da Terra, exibe muda de ip\u00ea plantada em parque urbano pr\u00f3ximo a Sol Nascente\"\/><\/div><div class=\"block--story-image__content\"><div itemprop=\"caption\" class=\"block--story-image__caption\">Larissa Brenda Cordeiro, presidente do Instituto Filhas da Terra, exibe muda de ip\u00ea plantada em parque urbano pr\u00f3ximo a Sol Nascente. O calor agrava sua asma e fibromialgia (Imagem: <a href=\"https:\/\/pozzebom.com.br\/\">Fabio Pozzebom<\/a> \/ Dialogue Earth)<\/div><\/div><\/div><meta itemprop=\"contentUrl\" content=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Larissa-Brenda-Cordeiro_Parque-Urbano-setor-O_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\"\/><meta itemprop=\"contentSize\" content=\"2 MB\"\/><meta itemprop=\"height\" content=\"1707\"\/><meta itemprop=\"width\" content=\"2560\"\/><meta itemprop=\"author\"\/><meta itemprop=\"representativeOfPage\" content=\"true\"\/><\/div>\n\n\n\n<p>Segundo Patricia Fabian, professora de sa\u00fade ambiental da Universidade de Boston, quem vive em ilhas de calor est\u00e1 mais exposto aos efeitos nocivos das altas temperaturas. \u201cQuanto mais quente o ambiente, maior o risco de impactos na sa\u00fade, incluindo doen\u00e7as cardiovasculares, problemas cognitivos, sintomas respirat\u00f3rios e at\u00e9 mesmo morte\u201d, explicou.&nbsp;<\/p>\n\n\n\n<p>Pesquisas conduzidas por ela e colegas na regi\u00e3o de Boston registraram <a href=\"https:\/\/www.bu.edu\/sph\/news\/articles\/2024\/patricia-fabian-op-ed-on-extreme-heat\/\">diferen\u00e7as de mais de 10\u00b0F (cerca de 5,5\u00b0C)<\/a> entre algumas comunidades, com as zonas mais quentes concentradas onde h\u00e1 pouco verde e muitas superf\u00edcies imperme\u00e1veis.<\/p>\n\n\n\n<p>Na esta\u00e7\u00e3o seca, algumas partes da regi\u00e3o central de Bras\u00edlia podem registrar at\u00e9 37,8\u00b0C de temperatura m\u00e1xima, enquanto Ceil\u00e2ndia (regi\u00e3o administrativa que incorporou Sol Nascente at\u00e9 2019) chega a 46,6\u00b0C. J\u00e1 a umidade relativa do ar cai de 11% em \u00e1reas arborizadas para 6,2% em Ceil\u00e2ndia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-protegendo-o-verde-que-sobrou\">Protegendo o verde que sobrou<\/h2>\n\n\n\n<p>Uma das poucas \u00e1reas verdes do Sol Nascente \u00e9 um remanescente do Parque Lagoinha, que vem sendo gradualmente desmatado por conta do avan\u00e7o de ocupa\u00e7\u00f5es. A \u00e1rea tamb\u00e9m carece de infraestrutura, o que impede seu uso para recrea\u00e7\u00e3o p\u00fablica.&nbsp;<\/p>\n\n\n\n<p>A presen\u00e7a de buritis indica abund\u00e2ncia de \u00e1gua subterr\u00e2nea, mas o local <a href=\"https:\/\/www.periodicos.rc.biblioteca.unesp.br\/index.php\/geociencias\/article\/view\/17684\/12796\">acumula<\/a> lixo, inclusive em nascentes, que se conectam ao <a href=\"https:\/\/www.periodicos.rc.biblioteca.unesp.br\/index.php\/geociencias\/article\/view\/17684\">rio Melchior<\/a> e \u00e0 Bacia do Descoberto, respons\u00e1veis por abastecer por <a href=\"https:\/\/www.ana.gov.br\/sar\/outros-sistemas-hidricos\/df\">mais de 60% do DF<\/a>.<\/p>\n\n\n\n<div class=\"wp-block-cd-story-image aligncenter block--story-image block--story-image--wide\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><div class=\"block--story-image__column\"><div class=\"block--story-image__image\"><img class=\"lazy\" data-src=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_rubbish-Lagoinha-park_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\" data-srcset=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_rubbish-Lagoinha-park_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-768x512.jpg 768w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_rubbish-Lagoinha-park_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1024x683.jpg 1024w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_rubbish-Lagoinha-park_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1400x934.jpg 1400w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_rubbish-Lagoinha-park_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1800x1200.jpg 2000w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_rubbish-Lagoinha-park_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\" data-sizes=\"(max-width: 600px) 768px, (max-width: 999px) 1024px, (max-width: 1400px) 1400px, (max-width: 2000px) 2000px, 2560px\" alt=\"Lixo espalhado por uma das poucas \u00e1reas verdes de Sol Nascente\"\/><\/div><div class=\"block--story-image__content\"><div itemprop=\"caption\" class=\"block--story-image__caption\">Lixo espalhado por uma das poucas \u00e1reas verdes de Sol Nascente, o Parque da Lagoinha. A presen\u00e7a de palmeiras como buritis indica abund\u00e2ncia de \u00e1gua subterr\u00e2nea, mas a \u00e1rea vem sendo polu\u00edda constantemente (Imagem: <a href=\"https:\/\/pozzebom.com.br\/\">Fabio Pozzebom<\/a> \/ Dialogue Earth)<\/div><\/div><\/div><meta itemprop=\"contentUrl\" content=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_rubbish-Lagoinha-park_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\"\/><meta itemprop=\"contentSize\" content=\"2 MB\"\/><meta itemprop=\"height\" content=\"1707\"\/><meta itemprop=\"width\" content=\"2560\"\/><meta itemprop=\"author\"\/><meta itemprop=\"representativeOfPage\" content=\"true\"\/><\/div>\n\n\n\n<div class=\"wp-block-cd-story-image aligncenter block--story-image block--story-image--wide\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><div class=\"block--story-image__column\"><div class=\"block--story-image__image\"><img class=\"lazy\" data-src=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_spring-Lagoinha-park-Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\" data-srcset=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_spring-Lagoinha-park-Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-768x512.jpg 768w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_spring-Lagoinha-park-Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1024x683.jpg 1024w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_spring-Lagoinha-park-Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1400x934.jpg 1400w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_spring-Lagoinha-park-Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1800x1200.jpg 2000w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_spring-Lagoinha-park-Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\" data-sizes=\"(max-width: 600px) 768px, (max-width: 999px) 1024px, (max-width: 1400px) 1400px, (max-width: 2000px) 2000px, 2560px\" alt=\"Nascentes no Parque da Lagoinha alimentam rio Melchior e bacia do Descoberto\"\/><\/div><div class=\"block--story-image__content\"><div itemprop=\"caption\" class=\"block--story-image__caption\">Nascentes no Parque da Lagoinha alimentam rio Melchior e bacia do Descoberto, respons\u00e1veis por abastecimento h\u00eddrico de mais de 60% do Distrito Federa (Imagem: <a href=\"https:\/\/pozzebom.com.br\/\">Fabio Pozzebom<\/a> \/ Dialogue Earth)<\/div><\/div><\/div><meta itemprop=\"contentUrl\" content=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_spring-Lagoinha-park-Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\"\/><meta itemprop=\"contentSize\" content=\"2 MB\"\/><meta itemprop=\"height\" content=\"1707\"\/><meta itemprop=\"width\" content=\"2560\"\/><meta itemprop=\"author\"\/><meta itemprop=\"representativeOfPage\" content=\"true\"\/><\/div>\n\n\n\n<p>Em dezembro de 2025, o DF aprovou um <a href=\"https:\/\/www.sinj.df.gov.br\/sinj\/Norma\/bd9ca8479a5d4ee4a2065190748760c3\/Lei_Complementar_1061_10_12_2025.html\">plano<\/a> para reduzir o d\u00e9ficit verde nas periferias. Para o caso do Sol Nascente, o governo informou ao <em>Dialogue Earth <\/em>que o in\u00edcio do plantio depende de obras de urbaniza\u00e7\u00e3o, j\u00e1 que as cal\u00e7adas estreitas e a falta de drenagem pluvial impediriam a sobreviv\u00eancia das mudas. Mas o governo n\u00e3o informou se e quando as obras ocorreriam.<\/p>\n\n\n\n<p>Por isso, Cordeiro e outros ativistas recorrem ao \u201cplantio de guerrilha\u201d, como ela descreve, em \u00e1reas como o Parque Lagoinha. Eles ignoram a proibi\u00e7\u00e3o de moradores plantarem mudas, imposta sob a justificativa de que a iniciativa oferece riscos \u00e0 fia\u00e7\u00e3o e \u00e0s tubula\u00e7\u00f5es. \u201cA gente fecha o olho e finge que n\u00e3o escutou. Se n\u00e3o plantarmos, quem vai?\u201d, questiona.&nbsp;<\/p>\n\n\n\n<p>Hoje, o parque \u00e9 um amplo gramado com poucas \u00e1rvores nativas, mas a expectativa \u00e9 que se torne uma \u00e1rea arborizada com mesas e quadras de esportes. \u201cNosso sonho \u00e9 que o Lagoinha vire um parque de verdade para que a popula\u00e7\u00e3o possa usufruir, assim como acontece no Plano Piloto\u201d, disse Cordeiro.&nbsp;<\/p>\n\n\n\n<p>Eles t\u00eam uma inspira\u00e7\u00e3o: no limite entre Sol Nascente e Ceil\u00e2ndia, a Floresta da Nasar\u00e9, como ficou conhecida, nasceu de um lix\u00e3o. Em 2009, a dona de casa Nasar\u00e9 Francisca da Silva come\u00e7ou a limpar sozinha o terreno p\u00fablico do tamanho de um campo de futebol em frente \u00e0 sua casa. \u201cAs pessoas jogavam de tudo, de restos de constru\u00e7\u00e3o a animais mortos\u201d, lembrou. \u201cEu olhava aquilo da minha porta e me dava tristeza\u201d.<\/p>\n\n\n\n<div class=\"wp-block-cd-story-image aligncenter block--story-image block--story-image--wide\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><div class=\"block--story-image__column\"><div class=\"block--story-image__image\"><img class=\"lazy\" data-src=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Nasare-Francisca-da-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-thumb.jpg\" data-srcset=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Nasare-Francisca-da-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-thumb-768x512.jpg 768w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Nasare-Francisca-da-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-thumb-1024x683.jpg 1024w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Nasare-Francisca-da-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-thumb.jpg\" data-sizes=\"(max-width: 600px) 768px, (max-width: 999px) 1024px, (max-width: 1400px) 1400px, (max-width: 2000px) 2000px, 1200px\" alt=\"Nasar\u00e9 Francisca da Silva rega horta na Floresta da Nasar\u00e9\"\/><\/div><div class=\"block--story-image__content\"><div itemprop=\"caption\" class=\"block--story-image__caption\">Nasar\u00e9 Francisca da Silva rega horta na Floresta da Nasar\u00e9, em Ceil\u00e2ndia, projeto agroflorestal criado por ela a partir de um lix\u00e3o (Imagem: <a href=\"https:\/\/pozzebom.com.br\/\">Fabio Pozzebom<\/a> \/ Dialogue Earth)<\/div><\/div><\/div><meta itemprop=\"contentUrl\" content=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Nasare-Francisca-da-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-thumb.jpg\"\/><meta itemprop=\"contentSize\" content=\"993 KB\"\/><meta itemprop=\"height\" content=\"800\"\/><meta itemprop=\"width\" content=\"1200\"\/><meta itemprop=\"author\"\/><meta itemprop=\"representativeOfPage\" content=\"true\"\/><\/div>\n\n\n\n<div class=\"wp-block-cd-story-image aligncenter block--story-image block--story-image--wide\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><div class=\"block--story-image__column\"><div class=\"block--story-image__image\"><img class=\"lazy\" data-src=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Floresta-de-Nasare_GDF-sign_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\" data-srcset=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Floresta-de-Nasare_GDF-sign_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-768x512.jpg 768w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Floresta-de-Nasare_GDF-sign_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1024x683.jpg 1024w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Floresta-de-Nasare_GDF-sign_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1400x934.jpg 1400w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Floresta-de-Nasare_GDF-sign_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1800x1200.jpg 2000w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Floresta-de-Nasare_GDF-sign_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\" data-sizes=\"(max-width: 600px) 768px, (max-width: 999px) 1024px, (max-width: 1400px) 1400px, (max-width: 2000px) 2000px, 2560px\" alt=\"Projeto da agrofloesta Floresta da Nasar\u00e9\"\/><\/div><div class=\"block--story-image__content\"><div itemprop=\"caption\" class=\"block--story-image__caption\">Em 2023, o projeto da agrofloesta foi reconhecido formalmente pelo governo do Distrito Federal, 14 anos ap\u00f3s o in\u00edcio do projeto (Imagem: <a href=\"https:\/\/pozzebom.com.br\/\">Fabio Pozzebom<\/a> \/ Dialogue Earth)<\/div><\/div><\/div><meta itemprop=\"contentUrl\" content=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_Floresta-de-Nasare_GDF-sign_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\"\/><meta itemprop=\"contentSize\" content=\"1 MB\"\/><meta itemprop=\"height\" content=\"1707\"\/><meta itemprop=\"width\" content=\"2560\"\/><meta itemprop=\"author\"\/><meta itemprop=\"representativeOfPage\" content=\"true\"\/><\/div>\n\n\n\n<div class=\"wp-block-cd-story-image aligncenter block--story-image block--story-image--wide\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"><div class=\"block--story-image__column\"><div class=\"block--story-image__image\"><img class=\"lazy\" data-src=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_marmoset-Floresta-de-Nasare-Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\" data-srcset=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_marmoset-Floresta-de-Nasare-Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-768x512.jpg 768w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_marmoset-Floresta-de-Nasare-Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1024x683.jpg 1024w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_marmoset-Floresta-de-Nasare-Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1400x934.jpg 1400w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_marmoset-Floresta-de-Nasare-Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-1800x1200.jpg 2000w, https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_marmoset-Floresta-de-Nasare-Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\" data-sizes=\"(max-width: 600px) 768px, (max-width: 999px) 1024px, (max-width: 1400px) 1400px, (max-width: 2000px) 2000px, 2560px\" alt=\"Sagui escondido entre galhos na Floresta da Nasar\u00e9\"\/><\/div><div class=\"block--story-image__content\"><div itemprop=\"caption\" class=\"block--story-image__caption\">Sagui escondido entre galhos na Floresta da Nasar\u00e9. A sombra das \u00e1rvores ameniza o calor nos dias mais quentes (Imagem: <a href=\"https:\/\/pozzebom.com.br\/\">Fabio Pozzebom<\/a> \/ Dialogue Earth)<\/div><\/div><\/div><meta itemprop=\"contentUrl\" content=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_PT_marmoset-Floresta-de-Nasare-Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth.jpg\"\/><meta itemprop=\"contentSize\" content=\"1 MB\"\/><meta itemprop=\"height\" content=\"1707\"\/><meta itemprop=\"width\" content=\"2560\"\/><meta itemprop=\"author\"\/><meta itemprop=\"representativeOfPage\" content=\"true\"\/><\/div>\n\n\n\n<p>Ela plantou a primeira muda na \u00e1rea que hoje vem se tornando uma agrofloresta, mantida por vizinhos, organiza\u00e7\u00f5es e pesquisadores da UnB. O cuidado dela com o terreno foi <a href=\"https:\/\/www.instagram.com\/p\/Cri4DCTrHMg\/?img_index=1\">formalizado<\/a> em 2023 pelo governo do DF por meio do <a href=\"https:\/\/www.sinj.df.gov.br\/sinj\/Norma\/33634c5082e7471fa38a72f48636b417\/exec_dec_39690_2019.html\">programa<\/a> Adote uma Pra\u00e7a, que permite a moradores e empresas cuidar de espa\u00e7os p\u00fablicos. A Floresta da Nasar\u00e9 segue sem investimento p\u00fablico, mas o termo garante reconhecimento oficial, reduzindo o risco de a \u00e1rea ser tomada ou o trabalho interrompido sem aviso.<\/p>\n\n\n\n<p>Hoje, a temperatura cai sob a copa das \u00e1rvores, e animais silvestres, como saguis, j\u00e1 apareceram. \u201cTodo mundo est\u00e1 livre para chegar aqui e se refrescar do calor\u201d, convida Silva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ilhas de calor nas favelas da capital brasileira aumentam riscos \u00e0 sa\u00fade \u2013 sintoma da desigualdade no acesso a \u00e1reas verdes em todo o mundo<\/p>\n","protected":false},"featured_media":60142221,"comment_status":"closed","ping_status":"closed","template":"","categories":[50039920,50039934],"tags":[50042415,50030002,50040046,50041503,50029705],"country":[50003526],"class_list":["post-60142339","photo_story","type-photo_story","status-publish","has-post-thumbnail","hentry","category-clima","category-justica","tag-adaptacao-ao-calor-extremo","tag-clima-extremo","tag-impactos-climaticos","tag-meios-de-subsistencia","tag-saude","country-brasil-pt-br"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.0 (Yoast SEO v26.0) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Periferia de Bras\u00edlia faz &#039;plantio de guerrilha&#039; contra o calor<\/title>\n<meta name=\"description\" content=\"Ilhas de calor nas favelas da capital brasileira aumentam riscos \u00e0 sa\u00fade \u2013 sintoma da desigualdade no acesso a \u00e1reas verdes em todo o mundo\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Periferia de Bras\u00edlia faz &#039;plantio de guerrilha&#039; contra o calor\" \/>\n<meta property=\"og:description\" content=\"Ilhas de calor nas favelas da capital brasileira aumentam riscos \u00e0 sa\u00fade \u2013 sintoma da desigualdade no acesso a \u00e1reas verdes em todo o mundo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/\" \/>\n<meta property=\"og:site_name\" content=\"Dialogue Earth\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T19:50:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_Nasare-Francisca-da-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-thumb.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/\",\"url\":\"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/\",\"name\":\"Periferia de Bras\u00edlia faz 'plantio de guerrilha' contra o calor\",\"isPartOf\":{\"@id\":\"https:\/\/dialogue.earth\/pt-br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_Nasare-Francisca-da-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-thumb.jpg\",\"datePublished\":\"2026-07-14T17:09:56+00:00\",\"dateModified\":\"2026-07-14T19:50:43+00:00\",\"description\":\"Ilhas de calor nas favelas da capital brasileira aumentam riscos \u00e0 sa\u00fade \u2013 sintoma da desigualdade no acesso a \u00e1reas verdes em todo o mundo\",\"breadcrumb\":{\"@id\":\"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/#primaryimage\",\"url\":\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_Nasare-Francisca-da-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-thumb.jpg\",\"contentUrl\":\"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_Nasare-Francisca-da-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-thumb.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Woman watering crops with hose in garden\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dialogue.earth\/pt-br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Periferia de Bras\u00edlia faz &#8216;plantio de guerrilha&#8217; contra o calor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dialogue.earth\/pt-br\/#website\",\"url\":\"https:\/\/dialogue.earth\/pt-br\/\",\"name\":\"Dialogue Earth\",\"description\":\"Dialogue Earth\",\"publisher\":{\"@id\":\"https:\/\/dialogue.earth\/pt-br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dialogue.earth\/pt-br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dialogue.earth\/pt-br\/#organization\",\"name\":\"\u5bf9\u8bdd\u5730\u7403\",\"url\":\"https:\/\/dialogue.earth\/pt-br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/dialogue.earth\/pt-br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dialogue.earth\/content\/uploads\/2024\/04\/Dialogue-Earth-Symbol-Logo_Black-Text.png\",\"contentUrl\":\"https:\/\/dialogue.earth\/content\/uploads\/2024\/04\/Dialogue-Earth-Symbol-Logo_Black-Text.png\",\"width\":256,\"height\":256,\"caption\":\"\u5bf9\u8bdd\u5730\u7403\"},\"image\":{\"@id\":\"https:\/\/dialogue.earth\/pt-br\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dialogueearth.americalatina\",\"https:\/\/twitter.com\/DialogueEarthBR\",\"https:\/\/www.linkedin.com\/company\/dialogueearth-americalatina\",\"https:\/\/www.instagram.com\/dialogue.earth_br\/\"],\"publishingPrinciples\":\"https:\/\/dialogue.earth\/en\/about\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Periferia de Bras\u00edlia faz 'plantio de guerrilha' contra o calor","description":"Ilhas de calor nas favelas da capital brasileira aumentam riscos \u00e0 sa\u00fade \u2013 sintoma da desigualdade no acesso a \u00e1reas verdes em todo o mundo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/","og_locale":"pt_BR","og_type":"article","og_title":"Periferia de Bras\u00edlia faz 'plantio de guerrilha' contra o calor","og_description":"Ilhas de calor nas favelas da capital brasileira aumentam riscos \u00e0 sa\u00fade \u2013 sintoma da desigualdade no acesso a \u00e1reas verdes em todo o mundo","og_url":"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/","og_site_name":"Dialogue Earth","article_modified_time":"2026-07-14T19:50:43+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_Nasare-Francisca-da-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-thumb.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/","url":"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/","name":"Periferia de Bras\u00edlia faz 'plantio de guerrilha' contra o calor","isPartOf":{"@id":"https:\/\/dialogue.earth\/pt-br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/#primaryimage"},"image":{"@id":"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/#primaryimage"},"thumbnailUrl":"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_Nasare-Francisca-da-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-thumb.jpg","datePublished":"2026-07-14T17:09:56+00:00","dateModified":"2026-07-14T19:50:43+00:00","description":"Ilhas de calor nas favelas da capital brasileira aumentam riscos \u00e0 sa\u00fade \u2013 sintoma da desigualdade no acesso a \u00e1reas verdes em todo o mundo","breadcrumb":{"@id":"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/#primaryimage","url":"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_Nasare-Francisca-da-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-thumb.jpg","contentUrl":"https:\/\/dialogue.earth\/content\/uploads\/2026\/07\/20260505_Nasare-Francisca-da-Silva_Sol-Nascente_Brasilia-Brazil_Fabio-Pozzebom_Dialogue-Earth-thumb.jpg","width":1200,"height":800,"caption":"Woman watering crops with hose in garden"},{"@type":"BreadcrumbList","@id":"https:\/\/dialogue.earth\/pt-br\/clima\/periferia-brasilia-plantio-guerrilha-calor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dialogue.earth\/pt-br\/"},{"@type":"ListItem","position":2,"name":"Periferia de Bras\u00edlia faz &#8216;plantio de guerrilha&#8217; contra o calor"}]},{"@type":"WebSite","@id":"https:\/\/dialogue.earth\/pt-br\/#website","url":"https:\/\/dialogue.earth\/pt-br\/","name":"Dialogue Earth","description":"Dialogue Earth","publisher":{"@id":"https:\/\/dialogue.earth\/pt-br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dialogue.earth\/pt-br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/dialogue.earth\/pt-br\/#organization","name":"\u5bf9\u8bdd\u5730\u7403","url":"https:\/\/dialogue.earth\/pt-br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/dialogue.earth\/pt-br\/#\/schema\/logo\/image\/","url":"https:\/\/dialogue.earth\/content\/uploads\/2024\/04\/Dialogue-Earth-Symbol-Logo_Black-Text.png","contentUrl":"https:\/\/dialogue.earth\/content\/uploads\/2024\/04\/Dialogue-Earth-Symbol-Logo_Black-Text.png","width":256,"height":256,"caption":"\u5bf9\u8bdd\u5730\u7403"},"image":{"@id":"https:\/\/dialogue.earth\/pt-br\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dialogueearth.americalatina","https:\/\/twitter.com\/DialogueEarthBR","https:\/\/www.linkedin.com\/company\/dialogueearth-americalatina","https:\/\/www.instagram.com\/dialogue.earth_br\/"],"publishingPrinciples":"https:\/\/dialogue.earth\/en\/about\/"}]}},"_links":{"self":[{"href":"https:\/\/dialogue.earth\/pt-br\/wp-json\/wp\/v2\/photo_story\/60142339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dialogue.earth\/pt-br\/wp-json\/wp\/v2\/photo_story"}],"about":[{"href":"https:\/\/dialogue.earth\/pt-br\/wp-json\/wp\/v2\/types\/photo_story"}],"replies":[{"embeddable":true,"href":"https:\/\/dialogue.earth\/pt-br\/wp-json\/wp\/v2\/comments?post=60142339"}],"version-history":[{"count":3,"href":"https:\/\/dialogue.earth\/pt-br\/wp-json\/wp\/v2\/photo_story\/60142339\/revisions"}],"predecessor-version":[{"id":60142587,"href":"https:\/\/dialogue.earth\/pt-br\/wp-json\/wp\/v2\/photo_story\/60142339\/revisions\/60142587"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dialogue.earth\/pt-br\/wp-json\/wp\/v2\/media\/60142221"}],"wp:attachment":[{"href":"https:\/\/dialogue.earth\/pt-br\/wp-json\/wp\/v2\/media?parent=60142339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dialogue.earth\/pt-br\/wp-json\/wp\/v2\/categories?post=60142339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dialogue.earth\/pt-br\/wp-json\/wp\/v2\/tags?post=60142339"},{"taxonomy":"country","embeddable":true,"href":"https:\/\/dialogue.earth\/pt-br\/wp-json\/wp\/v2\/country?post=60142339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}